{"id":8491,"date":"2019-08-21T13:40:25","date_gmt":"2019-08-21T17:40:25","guid":{"rendered":"https:\/\/equipelacroix.com\/raise-your-glass\/"},"modified":"2019-08-21T13:40:25","modified_gmt":"2019-08-21T17:40:25","slug":"raise-your-glass","status":"publish","type":"post","link":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/","title":{"rendered":"Raise your glass!"},"content":{"rendered":"<p>The wine industry is evolving and growing in popularity around the world. Gone are the days when Europe had the market\u2019s monopoly. Several countries and producers now stand out in the production of this highly-prized alcohol. Consumers are increasingly informed; they want to discover new products and try new great vintages. No wonder wine coolers and cellars are increasingly present in homes. Often associated with the pleasures of eating and celebrations, wine consumption is an activity that we like to share with family and friends.<\/p>\n<p> Here is a useful little guide to help you create a practical and stylish wine cellar.<\/p>\n<h2><strong>Wine Cooler Or Wine Cellar?<\/strong><\/h2>\n<p>Before choosing the type of layout to store your wine, you must know your needs. Are you an occasional drinker who wants to store your wine in an optimal environment? Or a wine enthusiast who likes to acquire a collection of bottles and age them? You will then be able to better estimate the space you need, depending on the number of bottles you wish to store.<\/p>\n<p>One of the main differences between a wine cooler and a wine cellar is its storage capacity. On average, a wine cooler holds between 20 and 400 bottles. It can be attached directly to an existing room in the house, such as a kitchen or dining room. It is possible to create a custom-made wine cooler or to purchase one instore. The watchword in a wine cooler\u2019s design is not to be afraid to dare. A wine cooler can quickly become an element of your decor. It can make a room look sophisticated, giving it a chic and sought-after look. Glass wine coolers are more and more popular. They allow you to separate two rooms without compromising luminosity.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-8395 size-full\" src=\"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cellier_en_verre_cover-1566409100.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cellier_en_verre_cover-1566409100.jpg 1000w, https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cellier_en_verre_cover-1566409100-300x200.jpg 300w, https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cellier_en_verre_cover-1566409100-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>If your passion and budget lead you to keep more than 400 bottles, it will then be preferable to have a wine cellar. It is, therefore, a complete room in your home, preferably located in the basement. It should be built to age your precious collections. The primary materials used in the design of a wine cellar are wood and stone. When lying down, wine bottles occupy a space of between 30 and 35 centimetres. Its conservation will be best with optimal environmental conditions. It is why it is advisable to keep the room temperature between 12 and 14 degrees Celsius, and humidity between 50 and 75%. If possible, keep the room in the dark and only open the light when you need to move around in it, as wine does not really like brightness. <\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-8397 size-full\" src=\"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cave_a_vin3-1566409481.jpg\" alt=\"\" width=\"940\" height=\"504\" srcset=\"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cave_a_vin3-1566409481.jpg 940w, https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cave_a_vin3-1566409481-300x161.jpg 300w, https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cave_a_vin3-1566409481-768x412.jpg 768w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/p>\n<h2><strong><br \/>\nWine Lovers, Get Ready! <\/strong><\/h2>\n<p>If you want to discover new grape varieties and try local products, do not miss the F\u00eate des vendanges Magog-Orford, the meeting place for wine lovers in the Eastern Townships. The event\u2019s 26th edition will take place on the weekends of August 31, September 1 and 2, and of September 7 and 8<\/p>\n<p><img decoding=\"async\" src=\"..\/files\/equipelacroix\/vendanges4-1566410363.jpg\" alt=\"\" \/><img decoding=\"async\" class=\"alignnone wp-image-8401 size-large\" src=\"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/vendanges4-1566410363-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/vendanges4-1566410363-1024x683.jpg 1024w, https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/vendanges4-1566410363-300x200.jpg 300w, https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/vendanges4-1566410363-768x512.jpg 768w, https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/vendanges4-1566410363-1536x1024.jpg 1536w, https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/vendanges4-1566410363-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>For more information and to get your tickets:\u00a0<a href=\"https:\/\/fetedesvendanges.com\/en\/\">https:\/\/fetedesvendanges.com\/en\/m<\/a><\/p>\n<p>Cheers!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The wine industry is evolving and growing in popularity around the world. Gone are the days when Europe had the market\u2019s monopoly. Several countries and producers now stand out in the production of &hellip;<\/p>\n","protected":false},"author":2,"featured_media":8394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raise your glass! | \u00c9quipe Lacroix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equipelacroix.com\/en\/raise-your-glass\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raise your glass! | \u00c9quipe Lacroix\" \/>\n<meta property=\"og:description\" content=\"The wine industry is evolving and growing in popularity around the world. Gone are the days when Europe had the market\u2019s monopoly. Several countries and producers now stand out in the production of &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equipelacroix.com\/en\/raise-your-glass\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Lacroix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/equipelacroix\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-21T17:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cellier_cover-1566410553-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julien Caron\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julien Caron\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/\"},\"author\":{\"name\":\"Julien Caron\",\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/#\\\/schema\\\/person\\\/31f52a64446444bf0528bd4a3ecc1b68\"},\"headline\":\"Raise your glass!\",\"datePublished\":\"2019-08-21T17:40:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/\"},\"wordCount\":490,\"publisher\":{\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equipelacroix.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cellier_cover-1566410553-scaled.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/\",\"url\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/\",\"name\":\"Raise your glass! | \u00c9quipe Lacroix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equipelacroix.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cellier_cover-1566410553-scaled.jpg\",\"datePublished\":\"2019-08-21T17:40:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/#primaryimage\",\"url\":\"https:\\\/\\\/equipelacroix.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cellier_cover-1566410553-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/equipelacroix.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cellier_cover-1566410553-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/raise-your-glass\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raise your glass!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/\",\"name\":\"\u00c9quipe Lacroix\",\"description\":\"Jos\u00e9, Jeremy et Mikael Lacroix, courtiers immobiliers \u00e0 Magog et Sherbrooke, Estrie | Sutton\",\"publisher\":{\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/#organization\",\"name\":\"\u00c9quipe Lacroix | Jos\u00e9, Jeremy et Mikael Lacroix, courtiers immobiliers \u00e0 Magog et Sherbrooke, Estrie | Sutton\",\"url\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/equipelacroix.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logotop.png\",\"contentUrl\":\"https:\\\/\\\/equipelacroix.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logotop.png\",\"width\":890,\"height\":179,\"caption\":\"\u00c9quipe Lacroix | Jos\u00e9, Jeremy et Mikael Lacroix, courtiers immobiliers \u00e0 Magog et Sherbrooke, Estrie | Sutton\"},\"image\":{\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/equipelacroix\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/#\\\/schema\\\/person\\\/31f52a64446444bf0528bd4a3ecc1b68\",\"name\":\"Julien Caron\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79883dae8deaabc598dedcc1e6926c52519647286eb32e10d5441ed2f5fac75d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79883dae8deaabc598dedcc1e6926c52519647286eb32e10d5441ed2f5fac75d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79883dae8deaabc598dedcc1e6926c52519647286eb32e10d5441ed2f5fac75d?s=96&d=mm&r=g\",\"caption\":\"Julien Caron\"},\"url\":\"https:\\\/\\\/equipelacroix.com\\\/en\\\/author\\\/vagzyotdps\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raise your glass! | \u00c9quipe Lacroix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/","og_locale":"en_US","og_type":"article","og_title":"Raise your glass! | \u00c9quipe Lacroix","og_description":"The wine industry is evolving and growing in popularity around the world. Gone are the days when Europe had the market\u2019s monopoly. Several countries and producers now stand out in the production of &hellip;","og_url":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/","og_site_name":"\u00c9quipe Lacroix","article_publisher":"https:\/\/www.facebook.com\/equipelacroix","article_published_time":"2019-08-21T17:40:25+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cellier_cover-1566410553-scaled.jpg","type":"image\/jpeg"}],"author":"Julien Caron","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Julien Caron","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/#article","isPartOf":{"@id":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/"},"author":{"name":"Julien Caron","@id":"https:\/\/equipelacroix.com\/en\/#\/schema\/person\/31f52a64446444bf0528bd4a3ecc1b68"},"headline":"Raise your glass!","datePublished":"2019-08-21T17:40:25+00:00","mainEntityOfPage":{"@id":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/"},"wordCount":490,"publisher":{"@id":"https:\/\/equipelacroix.com\/en\/#organization"},"image":{"@id":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/#primaryimage"},"thumbnailUrl":"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cellier_cover-1566410553-scaled.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/","url":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/","name":"Raise your glass! | \u00c9quipe Lacroix","isPartOf":{"@id":"https:\/\/equipelacroix.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/#primaryimage"},"image":{"@id":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/#primaryimage"},"thumbnailUrl":"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cellier_cover-1566410553-scaled.jpg","datePublished":"2019-08-21T17:40:25+00:00","breadcrumb":{"@id":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equipelacroix.com\/en\/raise-your-glass\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/#primaryimage","url":"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cellier_cover-1566410553-scaled.jpg","contentUrl":"https:\/\/equipelacroix.com\/wp-content\/uploads\/2024\/01\/cellier_cover-1566410553-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/equipelacroix.com\/en\/raise-your-glass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/equipelacroix.com\/en\/"},{"@type":"ListItem","position":2,"name":"Raise your glass!"}]},{"@type":"WebSite","@id":"https:\/\/equipelacroix.com\/en\/#website","url":"https:\/\/equipelacroix.com\/en\/","name":"\u00c9quipe Lacroix","description":"Jos\u00e9, Jeremy et Mikael Lacroix, courtiers immobiliers \u00e0 Magog et Sherbrooke, Estrie | Sutton","publisher":{"@id":"https:\/\/equipelacroix.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equipelacroix.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/equipelacroix.com\/en\/#organization","name":"\u00c9quipe Lacroix | Jos\u00e9, Jeremy et Mikael Lacroix, courtiers immobiliers \u00e0 Magog et Sherbrooke, Estrie | Sutton","url":"https:\/\/equipelacroix.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/equipelacroix.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/equipelacroix.com\/wp-content\/uploads\/2022\/06\/logotop.png","contentUrl":"https:\/\/equipelacroix.com\/wp-content\/uploads\/2022\/06\/logotop.png","width":890,"height":179,"caption":"\u00c9quipe Lacroix | Jos\u00e9, Jeremy et Mikael Lacroix, courtiers immobiliers \u00e0 Magog et Sherbrooke, Estrie | Sutton"},"image":{"@id":"https:\/\/equipelacroix.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/equipelacroix"]},{"@type":"Person","@id":"https:\/\/equipelacroix.com\/en\/#\/schema\/person\/31f52a64446444bf0528bd4a3ecc1b68","name":"Julien Caron","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/79883dae8deaabc598dedcc1e6926c52519647286eb32e10d5441ed2f5fac75d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/79883dae8deaabc598dedcc1e6926c52519647286eb32e10d5441ed2f5fac75d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79883dae8deaabc598dedcc1e6926c52519647286eb32e10d5441ed2f5fac75d?s=96&d=mm&r=g","caption":"Julien Caron"},"url":"https:\/\/equipelacroix.com\/en\/author\/vagzyotdps\/"}]}},"_links":{"self":[{"href":"https:\/\/equipelacroix.com\/en\/wp-json\/wp\/v2\/posts\/8491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equipelacroix.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equipelacroix.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equipelacroix.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/equipelacroix.com\/en\/wp-json\/wp\/v2\/comments?post=8491"}],"version-history":[{"count":0,"href":"https:\/\/equipelacroix.com\/en\/wp-json\/wp\/v2\/posts\/8491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equipelacroix.com\/en\/wp-json\/wp\/v2\/media\/8394"}],"wp:attachment":[{"href":"https:\/\/equipelacroix.com\/en\/wp-json\/wp\/v2\/media?parent=8491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equipelacroix.com\/en\/wp-json\/wp\/v2\/categories?post=8491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equipelacroix.com\/en\/wp-json\/wp\/v2\/tags?post=8491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}